{"id":267540,"date":"2023-09-21T11:59:12","date_gmt":"2023-09-21T09:59:12","guid":{"rendered":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2.jpg"},"modified":"2023-09-21T11:59:12","modified_gmt":"2023-09-21T09:59:12","slug":"berrik-2","status":"inherit","type":"attachment","link":"https:\/\/sagardoarenlurraldea.eus\/eu\/berrik-2\/","title":{"rendered":"Berrik (2)"},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"class_list":["post-267540","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Berrik (2) - Sagardoaren Lurraldea<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Berrik (2) - Sagardoaren Lurraldea\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sagardoarenlurraldea.eus\/eu\/berrik-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Sagardoaren Lurraldea\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sagardoarenlurraldea\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sagardoarenlurraldea.eus\/eu\/berrik-2\/\",\"url\":\"https:\/\/sagardoarenlurraldea.eus\/eu\/berrik-2\/\",\"name\":\"Berrik (2) - Sagardoaren Lurraldea\",\"isPartOf\":{\"@id\":\"https:\/\/sagardoarenlurraldea.eus\/eu\/#website\"},\"datePublished\":\"2023-09-21T09:59:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sagardoarenlurraldea.eus\/eu\/berrik-2\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sagardoarenlurraldea.eus\/eu\/berrik-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sagardoarenlurraldea.eus\/eu\/berrik-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/sagardoarenlurraldea.eus\/eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Berrik (2)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sagardoarenlurraldea.eus\/eu\/#website\",\"url\":\"https:\/\/sagardoarenlurraldea.eus\/eu\/\",\"name\":\"Sagardoaren Lurraldea\",\"description\":\"El territorio de la sidra\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sagardoarenlurraldea.eus\/eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Berrik (2) - Sagardoaren Lurraldea","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Berrik (2) - Sagardoaren Lurraldea","og_url":"https:\/\/sagardoarenlurraldea.eus\/eu\/berrik-2\/","og_site_name":"Sagardoaren Lurraldea","article_publisher":"https:\/\/www.facebook.com\/sagardoarenlurraldea","og_image":[{"width":2560,"height":1708,"url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sagardoarenlurraldea.eus\/eu\/berrik-2\/","url":"https:\/\/sagardoarenlurraldea.eus\/eu\/berrik-2\/","name":"Berrik (2) - Sagardoaren Lurraldea","isPartOf":{"@id":"https:\/\/sagardoarenlurraldea.eus\/eu\/#website"},"datePublished":"2023-09-21T09:59:12+00:00","breadcrumb":{"@id":"https:\/\/sagardoarenlurraldea.eus\/eu\/berrik-2\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sagardoarenlurraldea.eus\/eu\/berrik-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sagardoarenlurraldea.eus\/eu\/berrik-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/sagardoarenlurraldea.eus\/eu\/"},{"@type":"ListItem","position":2,"name":"Berrik (2)"}]},{"@type":"WebSite","@id":"https:\/\/sagardoarenlurraldea.eus\/eu\/#website","url":"https:\/\/sagardoarenlurraldea.eus\/eu\/","name":"Sagardoaren Lurraldea","description":"El territorio de la sidra","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sagardoarenlurraldea.eus\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1708,"file":"2023\/09\/Berrik-2-scaled.jpg","filesize":598656,"sizes":{"medium":{"file":"Berrik-2-300x200.jpg","width":300,"height":200,"filesize":22891,"mime_type":"image\/jpeg","source_url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-300x200.jpg"},"large":{"file":"Berrik-2-1024x683.jpg","width":1024,"height":683,"filesize":150711,"mime_type":"image\/jpeg","source_url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-1024x683.jpg"},"thumbnail":{"file":"Berrik-2-150x100.jpg","width":150,"height":100,"filesize":7635,"mime_type":"image\/jpeg","source_url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-150x100.jpg"},"medium_large":{"file":"Berrik-2-768x512.jpg","width":768,"height":512,"filesize":97172,"mime_type":"image\/jpeg","source_url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-768x512.jpg"},"1536x1536":{"file":"Berrik-2-1536x1025.jpg","width":1536,"height":1025,"filesize":277901,"mime_type":"image\/jpeg","source_url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-1536x1025.jpg"},"2048x2048":{"file":"Berrik-2-2048x1366.jpg","width":2048,"height":1366,"filesize":426735,"mime_type":"image\/jpeg","source_url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-2048x1366.jpg"},"et-pb-post-main-image":{"file":"Berrik-2-400x250.jpg","width":400,"height":250,"filesize":33940,"mime_type":"image\/jpeg","source_url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-400x250.jpg"},"et-pb-post-main-image-fullwidth":{"file":"Berrik-2-1080x675.jpg","width":1080,"height":675,"filesize":154175,"mime_type":"image\/jpeg","source_url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-1080x675.jpg"},"et-pb-portfolio-image":{"file":"Berrik-2-400x284.jpg","width":400,"height":284,"filesize":37056,"mime_type":"image\/jpeg","source_url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-400x284.jpg"},"et-pb-portfolio-module-image":{"file":"Berrik-2-510x382.jpg","width":510,"height":382,"filesize":55597,"mime_type":"image\/jpeg","source_url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-510x382.jpg"},"et-pb-portfolio-image-single":{"file":"Berrik-2-1080x720.jpg","width":1080,"height":720,"filesize":163066,"mime_type":"image\/jpeg","source_url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-1080x720.jpg"},"et-pb-gallery-module-image-portrait":{"file":"Berrik-2-400x516.jpg","width":400,"height":516,"filesize":52984,"mime_type":"image\/jpeg","source_url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-400x516.jpg"},"et-pb-post-main-image-fullwidth-large":{"file":"Berrik-2-2880x1800.jpg","width":2880,"height":1800,"filesize":675355,"mime_type":"image\/jpeg","source_url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-2880x1800.jpg"},"et-pb-image--responsive--desktop":{"file":"Berrik-2-1280x854.jpg","width":1280,"height":854,"filesize":210577,"mime_type":"image\/jpeg","source_url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-1280x854.jpg"},"et-pb-image--responsive--tablet":{"file":"Berrik-2-980x654.jpg","width":980,"height":654,"filesize":141657,"mime_type":"image\/jpeg","source_url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-980x654.jpg"},"et-pb-image--responsive--phone":{"file":"Berrik-2-480x320.jpg","width":480,"height":320,"filesize":47222,"mime_type":"image\/jpeg","source_url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-480x320.jpg"},"woocommerce_thumbnail":{"file":"Berrik-2-400x300.jpg","width":400,"height":300,"filesize":38419,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-400x300.jpg"},"woocommerce_single":{"file":"Berrik-2-510x340.jpg","width":510,"height":340,"filesize":52627,"mime_type":"image\/jpeg","source_url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-510x340.jpg"},"woocommerce_gallery_thumbnail":{"file":"Berrik-2-100x100.jpg","width":100,"height":100,"filesize":5509,"mime_type":"image\/jpeg","source_url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-100x100.jpg"},"shop_catalog":{"file":"Berrik-2-400x300.jpg","width":400,"height":300,"filesize":38419,"mime_type":"image\/jpeg","source_url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-400x300.jpg"},"shop_single":{"file":"Berrik-2-510x340.jpg","width":510,"height":340,"filesize":52627,"mime_type":"image\/jpeg","source_url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-510x340.jpg"},"shop_thumbnail":{"file":"Berrik-2-100x100.jpg","width":100,"height":100,"filesize":5509,"mime_type":"image\/jpeg","source_url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-100x100.jpg"},"full":{"file":"Berrik-2-scaled.jpg","width":2560,"height":1708,"mime_type":"image\/jpeg","source_url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-scaled.jpg"}},"image_meta":{"aperture":"1.8","credit":"","camera":"ILCE-7RM2","caption":"","created_timestamp":"1637406814","copyright":"","focal_length":"50","iso":"320","shutter_speed":"0.003125","title":"","orientation":"1","keywords":[]},"original_image":"Berrik-2.jpg"},"post":null,"source_url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2023\/09\/Berrik-2-scaled.jpg","_links":{"self":[{"href":"https:\/\/sagardoarenlurraldea.eus\/eu\/wp-json\/wp\/v2\/media\/267540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sagardoarenlurraldea.eus\/eu\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/sagardoarenlurraldea.eus\/eu\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/sagardoarenlurraldea.eus\/eu\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/sagardoarenlurraldea.eus\/eu\/wp-json\/wp\/v2\/comments?post=267540"}]}}