{"id":17680,"date":"2012-09-16T00:00:00","date_gmt":"2012-09-15T22:00:00","guid":{"rendered":"http:\/\/www.sagardoarenlurraldea.eus\/blog\/pintxo-pote-en-los-bares-de-astigarraga\/"},"modified":"2012-09-16T00:00:00","modified_gmt":"2012-09-15T22:00:00","slug":"pintxo-pote-en-los-bares-de-astigarraga","status":"publish","type":"post","link":"https:\/\/sagardoarenlurraldea.eus\/es\/blog\/pintxo-pote-en-los-bares-de-astigarraga\/","title":{"rendered":"Pintxo-pote en los bares de Astigarraga."},"content":{"rendered":"<p><a href=\"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2012\/09\/admin-ajax.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-2761\" alt=\"admin-ajax\" src=\"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2012\/09\/admin-ajax-300x201.jpeg\" width=\"300\" height=\"201\" srcset=\"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2012\/09\/admin-ajax-300x201.jpeg 300w, https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2012\/09\/admin-ajax.jpeg 350w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Con la finalidad de promover la gastronom\u00eda local y sumar una oferta culinaria basada en la manzana aut\u00f3ctona a la <strong>XII. edici\u00f3n de Sagar Uzta<\/strong>, los <strong>Hosteleros de Astigarraga ofrecer\u00e1n a los visitantes un pintxo-pote con pintxos elaborados con derivados de la manzana<\/strong>.<\/p>\n<p>Por tercer a\u00f1o consecutivo, los Hosteleros de Astigarraga se suman a la celebraci\u00f3n de la fiesta Sagar Uzta ofreciendo una oferta culinaria basada en la manzana aut\u00f3ctona y sus derivados.<\/p>\n<p>De esta forma, los <strong>bares Ikatza, Bukoi, The Robin, Sagartxo, Irati, Kupela, Txotx, Ibai-Lur, Txiki, Ekaitz y Pastoriza <\/strong>ofrecer\u00e1n el <strong>27 de septiembre un pintxo-pote entre las 19:00-21:00<\/strong>, donde se podr\u00e1n degustar diferentes <strong>pintxos inspirados en la manzana y sus derivados <\/strong>en originales creaciones.<\/p>\n<p>Adem\u00e1s de este pintxo-pote, en los bares<strong> se expondran las fotos ganadoras de las anteriores ediciones del Rally fotogr\u00e1fico Sagar Uzta<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la finalidad de promover la gastronom\u00eda local y sumar una oferta culinaria basada en la manzana aut\u00f3ctona a la XII. edici\u00f3n de Sagar Uzta, los Hosteleros de Astigarraga ofrecer\u00e1n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2083,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[246,252],"tags":[393,420,462,696,1425,1428,1676,1794,1947],"class_list":["post-17680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gastronomia","category-manzana","tag-argazki-erakusketa","tag-astigarraga","tag-bares","tag-derivados-de-la-manzana","tag-pintxo-pote","tag-pintxos-elaborados-con-manzana","tag-sagarrekin-egindako-pintxoak","tag-tabernak","tag-xii-sagar-uzta"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pintxo-pote en los bares de Astigarraga. - Sagardoaren Lurraldea<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sagardoarenlurraldea.eus\/es\/blog\/pintxo-pote-en-los-bares-de-astigarraga\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pintxo-pote en los bares de Astigarraga. - Sagardoaren Lurraldea\" \/>\n<meta property=\"og:description\" content=\"Con la finalidad de promover la gastronom\u00eda local y sumar una oferta culinaria basada en la manzana aut\u00f3ctona a la XII. edici\u00f3n de Sagar Uzta, los Hosteleros de Astigarraga ofrecer\u00e1n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sagardoarenlurraldea.eus\/es\/blog\/pintxo-pote-en-los-bares-de-astigarraga\/\" \/>\n<meta property=\"og:site_name\" content=\"Sagardoaren Lurraldea\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sagardoarenlurraldea\" \/>\n<meta property=\"article:published_time\" content=\"2012-09-15T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2012\/09\/pintxo-pote2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"235\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mikel Ecenarro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mikel Ecenarro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sagardoarenlurraldea.eus\/es\/blog\/pintxo-pote-en-los-bares-de-astigarraga\/\",\"url\":\"https:\/\/sagardoarenlurraldea.eus\/es\/blog\/pintxo-pote-en-los-bares-de-astigarraga\/\",\"name\":\"Pintxo-pote en los bares de Astigarraga. - Sagardoaren Lurraldea\",\"isPartOf\":{\"@id\":\"https:\/\/sagardoarenlurraldea.eus\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sagardoarenlurraldea.eus\/es\/blog\/pintxo-pote-en-los-bares-de-astigarraga\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sagardoarenlurraldea.eus\/es\/blog\/pintxo-pote-en-los-bares-de-astigarraga\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2012\/09\/pintxo-pote2.jpg\",\"datePublished\":\"2012-09-15T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/sagardoarenlurraldea.eus\/es\/#\/schema\/person\/9e9a225eda321f17256838c2fcba65a7\"},\"breadcrumb\":{\"@id\":\"https:\/\/sagardoarenlurraldea.eus\/es\/blog\/pintxo-pote-en-los-bares-de-astigarraga\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sagardoarenlurraldea.eus\/es\/blog\/pintxo-pote-en-los-bares-de-astigarraga\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sagardoarenlurraldea.eus\/es\/blog\/pintxo-pote-en-los-bares-de-astigarraga\/#primaryimage\",\"url\":\"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2012\/09\/pintxo-pote2.jpg\",\"contentUrl\":\"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2012\/09\/pintxo-pote2.jpg\",\"width\":350,\"height\":235},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sagardoarenlurraldea.eus\/es\/blog\/pintxo-pote-en-los-bares-de-astigarraga\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/sagardoarenlurraldea.eus\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pintxo-pote en los bares de Astigarraga.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sagardoarenlurraldea.eus\/es\/#website\",\"url\":\"https:\/\/sagardoarenlurraldea.eus\/es\/\",\"name\":\"Sagardoaren Lurraldea\",\"description\":\"El territorio de la sidra\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sagardoarenlurraldea.eus\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/sagardoarenlurraldea.eus\/es\/#\/schema\/person\/9e9a225eda321f17256838c2fcba65a7\",\"name\":\"Mikel Ecenarro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sagardoarenlurraldea.eus\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1170400e3ac60954a47797ced4deed6bcd49cf85a03b7abd291d8f8be059bd1d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1170400e3ac60954a47797ced4deed6bcd49cf85a03b7abd291d8f8be059bd1d?s=96&d=mm&r=g\",\"caption\":\"Mikel Ecenarro\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pintxo-pote en los bares de Astigarraga. - Sagardoaren Lurraldea","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sagardoarenlurraldea.eus\/es\/blog\/pintxo-pote-en-los-bares-de-astigarraga\/","og_locale":"es_ES","og_type":"article","og_title":"Pintxo-pote en los bares de Astigarraga. - Sagardoaren Lurraldea","og_description":"Con la finalidad de promover la gastronom\u00eda local y sumar una oferta culinaria basada en la manzana aut\u00f3ctona a la XII. edici\u00f3n de Sagar Uzta, los Hosteleros de Astigarraga ofrecer\u00e1n [&hellip;]","og_url":"https:\/\/sagardoarenlurraldea.eus\/es\/blog\/pintxo-pote-en-los-bares-de-astigarraga\/","og_site_name":"Sagardoaren Lurraldea","article_publisher":"https:\/\/www.facebook.com\/sagardoarenlurraldea","article_published_time":"2012-09-15T22:00:00+00:00","og_image":[{"width":350,"height":235,"url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2012\/09\/pintxo-pote2.jpg","type":"image\/jpeg"}],"author":"Mikel Ecenarro","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mikel Ecenarro","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sagardoarenlurraldea.eus\/es\/blog\/pintxo-pote-en-los-bares-de-astigarraga\/","url":"https:\/\/sagardoarenlurraldea.eus\/es\/blog\/pintxo-pote-en-los-bares-de-astigarraga\/","name":"Pintxo-pote en los bares de Astigarraga. - Sagardoaren Lurraldea","isPartOf":{"@id":"https:\/\/sagardoarenlurraldea.eus\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sagardoarenlurraldea.eus\/es\/blog\/pintxo-pote-en-los-bares-de-astigarraga\/#primaryimage"},"image":{"@id":"https:\/\/sagardoarenlurraldea.eus\/es\/blog\/pintxo-pote-en-los-bares-de-astigarraga\/#primaryimage"},"thumbnailUrl":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2012\/09\/pintxo-pote2.jpg","datePublished":"2012-09-15T22:00:00+00:00","author":{"@id":"https:\/\/sagardoarenlurraldea.eus\/es\/#\/schema\/person\/9e9a225eda321f17256838c2fcba65a7"},"breadcrumb":{"@id":"https:\/\/sagardoarenlurraldea.eus\/es\/blog\/pintxo-pote-en-los-bares-de-astigarraga\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sagardoarenlurraldea.eus\/es\/blog\/pintxo-pote-en-los-bares-de-astigarraga\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sagardoarenlurraldea.eus\/es\/blog\/pintxo-pote-en-los-bares-de-astigarraga\/#primaryimage","url":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2012\/09\/pintxo-pote2.jpg","contentUrl":"https:\/\/sagardoarenlurraldea.eus\/wp-content\/uploads\/2012\/09\/pintxo-pote2.jpg","width":350,"height":235},{"@type":"BreadcrumbList","@id":"https:\/\/sagardoarenlurraldea.eus\/es\/blog\/pintxo-pote-en-los-bares-de-astigarraga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/sagardoarenlurraldea.eus\/es\/"},{"@type":"ListItem","position":2,"name":"Pintxo-pote en los bares de Astigarraga."}]},{"@type":"WebSite","@id":"https:\/\/sagardoarenlurraldea.eus\/es\/#website","url":"https:\/\/sagardoarenlurraldea.eus\/es\/","name":"Sagardoaren Lurraldea","description":"El territorio de la sidra","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sagardoarenlurraldea.eus\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sagardoarenlurraldea.eus\/es\/#\/schema\/person\/9e9a225eda321f17256838c2fcba65a7","name":"Mikel Ecenarro","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sagardoarenlurraldea.eus\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1170400e3ac60954a47797ced4deed6bcd49cf85a03b7abd291d8f8be059bd1d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1170400e3ac60954a47797ced4deed6bcd49cf85a03b7abd291d8f8be059bd1d?s=96&d=mm&r=g","caption":"Mikel Ecenarro"}}]}},"_links":{"self":[{"href":"https:\/\/sagardoarenlurraldea.eus\/es\/wp-json\/wp\/v2\/posts\/17680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sagardoarenlurraldea.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sagardoarenlurraldea.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sagardoarenlurraldea.eus\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sagardoarenlurraldea.eus\/es\/wp-json\/wp\/v2\/comments?post=17680"}],"version-history":[{"count":0,"href":"https:\/\/sagardoarenlurraldea.eus\/es\/wp-json\/wp\/v2\/posts\/17680\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sagardoarenlurraldea.eus\/es\/wp-json\/wp\/v2\/media\/2083"}],"wp:attachment":[{"href":"https:\/\/sagardoarenlurraldea.eus\/es\/wp-json\/wp\/v2\/media?parent=17680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sagardoarenlurraldea.eus\/es\/wp-json\/wp\/v2\/categories?post=17680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sagardoarenlurraldea.eus\/es\/wp-json\/wp\/v2\/tags?post=17680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}